{"id":221,"date":"2011-09-24T21:37:46","date_gmt":"2011-09-25T00:37:46","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=221"},"modified":"2011-09-24T21:49:22","modified_gmt":"2011-09-25T00:49:22","slug":"o-abandono-do-mundo-real","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2011\/09\/24\/o-abandono-do-mundo-real\/","title":{"rendered":"O abandono do mundo real"},"content":{"rendered":"<p>Ultimamente est\u00e1 ficando cada vez mais f\u00e1cil ver pessoas que conhe\u00e7o vivendo em um mundo virtual. Pior que n\u00e3o \u00e9 s\u00f3 para fazer as coisas necess\u00e1rias, estas pessoas est\u00e3o ficando a maior parte do tempo \u00e0 frente do computador, em redes sociais e jogos online, se divertindo (a\u00ed tudo bem), mas tamb\u00e9m arrumando confus\u00f5es, brigas, descontentamentos, decep\u00e7\u00f5es, etc. E n\u00e3o tomam os devidos cuidados com a privacidade e seguran\u00e7a, postando tudo sobre as pr\u00f3prias intimidades.<\/p>\n<p>Est\u00e1 cada vez mais dif\u00edcil ver as pessoas que conhe\u00e7o dispostas a viver um mundo real, passear pelas ruas, descobrir novas cidades e difentes culturas.<\/p>\n<p>Estou cada vez mais ficando a maior parte do tempo sozinho, viajando e passeando sem a presen\u00e7a de pessoas que poderiam estar me acompanhando, mas est\u00e3o com certeza usando um computador, n\u00e3o sabendo se est\u00e1 chovendo, se \u00e9 noite ou est\u00e1 frio, ou s\u00f3 sabem isto olhando por algum site de meteorologia.<\/p>\n<p>J\u00e1 tive oportunidade de conhecer pessoas que dizem n\u00e3o ter tempo para uma conversa s\u00f3 para correr para um computador mais pr\u00f3ximo para conversar com algum &#8220;ser online&#8221;.<\/p>\n<p>Ser\u00e1 que sou eu quem estou por fora?<\/p>\n<p>Adoro tecnologia, gosto muito de estudar inform\u00e1tica e tecnologia da informa\u00e7\u00e3o, nem por isso deixo a minha vida de lado para criar uma &#8220;fazenda virtual&#8221;, gastando horas \u00fateis da minha vida se pedindo que pessoas visitem meu &#8220;boteco online&#8221; s\u00f3 para ganhar &#8220;moedinhas&#8221;, ou sei l\u00e1 que tranqueira pode se adquirir com isso.<\/p>\n<p>Uso, e muito, a internet, mas minha vida \u00e9 real!<\/p>\n<p>Para quem me conhece, e sabe dos lugares que fotografei, entende que gosto de explorar o mundo real. Uso a tecnologia virtual como meio de divulga\u00e7\u00e3o, informando que h\u00e1 muito o que se ver pelo mundo, e h\u00e1 muitas coisas legais para se fazer, e uso meu site para mostrar o que fiz.<\/p>\n<p>Algu\u00e9m topa a se aventurar comigo? Desligue o computador e venha!<\/p>\n<p style=\"text-align: center;\"><a href=\"http:\/\/mariano.viveiros.nom.br\/wpss\/wp-content\/uploads\/2011\/09\/farmville.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-231\" title=\"Vida virtualizada\" src=\"http:\/\/mariano.viveiros.nom.br\/wpss\/wp-content\/uploads\/2011\/09\/farmville-300x97.png\" alt=\"\" width=\"300\" height=\"97\" srcset=\"https:\/\/mariano.viveiros.nom.br\/wpss\/wp-content\/uploads\/2011\/09\/farmville-300x97.png 300w, https:\/\/mariano.viveiros.nom.br\/wpss\/wp-content\/uploads\/2011\/09\/farmville.png 684w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ultimamente est\u00e1 ficando cada vez mais f\u00e1cil ver pessoas que conhe\u00e7o vivendo em um mundo virtual. Pior que n\u00e3o \u00e9 s\u00f3 para fazer as coisas necess\u00e1rias, estas pessoas est\u00e3o ficando a maior parte do tempo \u00e0 frente do computador, em redes sociais e jogos online, se divertindo (a\u00ed tudo bem), mas tamb\u00e9m arrumando confus\u00f5es, brigas, &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mariano.viveiros.nom.br\/blog\/2011\/09\/24\/o-abandono-do-mundo-real\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;O abandono do mundo real&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[104,105,106,107,30,35],"class_list":["post-221","post","type-post","status-publish","format-standard","hentry","category-vida","tag-comportamento","tag-internet","tag-mundo-real","tag-mundo-virtual","tag-viagem","tag-vida"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/221","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=221"}],"version-history":[{"count":6,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/221\/revisions"}],"predecessor-version":[{"id":228,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/221\/revisions\/228"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=221"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=221"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=221"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}