{"id":296,"date":"2012-11-25T23:15:34","date_gmt":"2012-11-26T01:15:34","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=296"},"modified":"2012-11-25T23:15:34","modified_gmt":"2012-11-26T01:15:34","slug":"agradecimentos","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2012\/11\/25\/agradecimentos\/","title":{"rendered":"Agradecimentos"},"content":{"rendered":"<p>Agrade\u00e7o a todos que leem as mensagens aqui postadas.<\/p>\n<p>Acompanho a visita\u00e7\u00e3o por aqui e por fora e vejo que h\u00e1 um certo interesse pelo que escrevo.<\/p>\n<p>Procuro, do meu jeito simples, postar um pouco do que acontece em minha vida, compartilhando experi\u00eancias.<\/p>\n<p>\ud83d\ude09<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Agrade\u00e7o a todos que leem as mensagens aqui postadas. Acompanho a visita\u00e7\u00e3o por aqui e por fora e vejo que h\u00e1 um certo interesse pelo que escrevo. Procuro, do meu jeito simples, postar um pouco do que acontece em minha vida, compartilhando experi\u00eancias. \ud83d\ude09<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[159,160],"class_list":["post-296","post","type-post","status-publish","format-standard","hentry","category-vida","tag-agradecimentos","tag-postagem"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/296","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=296"}],"version-history":[{"count":1,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/296\/revisions"}],"predecessor-version":[{"id":297,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/296\/revisions\/297"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=296"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=296"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=296"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}