{"id":320,"date":"2013-08-20T20:21:22","date_gmt":"2013-08-20T23:21:22","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=320"},"modified":"2013-08-20T20:21:22","modified_gmt":"2013-08-20T23:21:22","slug":"maracatu","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2013\/08\/20\/maracatu\/","title":{"rendered":"Maracatu"},"content":{"rendered":"<p>A curiosidade \u00e0s vezes me faz experimentar coisas novas, e a novidade agora \u00e9 o maracatu.<\/p>\n<p>N\u00e3o sei o que deu na minha cabe\u00e7a de programar um final de semana s\u00f3 para conhecer o maracatu. Tudo bem que eu queria entender melhor o que \u00e9 para n\u00e3o confundir com outras coisas, e ap\u00f3s a indica\u00e7\u00e3o de um lugar decidi investigar.<\/p>\n<p>Conheci o Bloco de Pedra, onde ensaiam e oferecem cursos, possuem oficina aberta, etc. Faz parte do projeto Calo na M\u00e3o. Mais detalhes veja no site indicado abaixo.<\/p>\n<p>Primeira coisa que me atraiu no maracatu: o som das alfaias! A vontade de toc\u00e1-las quase me causou um enfarto. Imagina a vizinhan\u00e7a da Escola Estadual Alves Cruz suportando tudo isso, todos os s\u00e1bados quando h\u00e1 o curso.<\/p>\n<p>At\u00e9 me aprofundar mais no assunto o interesse meu era fazer barulho! \ud83d\ude00 Mas vi que haviam outros motivos muito interessantes, e que fez aumentar a minha frequ\u00eancia de participa\u00e7\u00e3o no maracatu, fazendo at\u00e9 com que eu me inscrevesse em um curso, e logicamente nas aulas de alfaia.<\/p>\n<p>O\u00a0melhor de participar de tudo isso \u00e9 conhecer um pouco mais da hist\u00f3ria do maracatu. Claro que n\u00e3o tenho como, por enquanto, colocar muitas informa\u00e7\u00f5es aqui em meu &#8220;blog&#8221;, mas alguma coisa postarei:<\/p>\n<ul>\n<li>A origem do maracatu \u00e9 brasileira, mais precisamente do Pernambuco;<\/li>\n<li>Existem v\u00e1rias na\u00e7\u00f5es de maracatu, por exemplo Estrela Brilhante de Igarassu, Porto Rico, etc;<\/li>\n<li>\u00c9 praticado em v\u00e1rios pa\u00edses;<\/li>\n<li>Por motivos religiosos foi proibido em alguns lugares, e muitas pessoas discriminam negativamente.<\/li>\n<\/ul>\n<p>Participar desse projeto \u00e9 muito bom e est\u00e1 me fazendo muito bem! \ud83d\ude42<\/p>\n<p>Para maiores informa\u00e7\u00f5es:<\/p>\n<p><a href=\"http:\/\/blocodepedra.maracatu.org.br\">http:\/\/blocodepedra.maracatu.org.br<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A curiosidade \u00e0s vezes me faz experimentar coisas novas, e a novidade agora \u00e9 o maracatu. N\u00e3o sei o que deu na minha cabe\u00e7a de programar um final de semana s\u00f3 para conhecer o maracatu. Tudo bem que eu queria entender melhor o que \u00e9 para n\u00e3o confundir com outras coisas, e ap\u00f3s a indica\u00e7\u00e3o &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mariano.viveiros.nom.br\/blog\/2013\/08\/20\/maracatu\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;Maracatu&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[173,174,175,177,178,176,179,180],"class_list":["post-320","post","type-post","status-publish","format-standard","hentry","category-vida","tag-alfaia","tag-bloco-de-pedra","tag-calo-na-mao","tag-estados-unidos","tag-manhattan","tag-maracatu","tag-new-york","tag-nyc"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/320","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=320"}],"version-history":[{"count":2,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/320\/revisions"}],"predecessor-version":[{"id":326,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/320\/revisions\/326"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=320"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=320"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=320"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}