{"id":322,"date":"2013-08-20T20:07:49","date_gmt":"2013-08-20T23:07:49","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=322"},"modified":"2013-08-20T20:09:17","modified_gmt":"2013-08-20T23:09:17","slug":"new-york-eu-fui","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2013\/08\/20\/new-york-eu-fui\/","title":{"rendered":"New York &#8211; Eu fui!"},"content":{"rendered":"<p>De todas as minhas viagens a mais dif\u00edcil seria essa, se eu n\u00e3o fizesse um planejamento antes. E n\u00e3o \u00e9 que foi f\u00e1cil!<br \/>\nA facilidade se deve ao trabalho que tive anos antes de ir, desde os estudos da l\u00edngua inglesa at\u00e9 o dinheiro poupado para poder bancar tudo.<\/p>\n<p>Agora, sobre New York: do mesmo jeito que em outras cidades por onde passei, andei pelas ruas normalmente. Com dinheiro no bolso o suficiente para os gastos b\u00e1sicos fiz o que tinha que fazer. N\u00e3o conheci todos os lugares que gostaria, mas senti um pouco de como \u00e9 esta cidade.<\/p>\n<p>Os pr\u00e9dios s\u00e3o mais altos que os de S\u00e3o Paulo. Visitar o Empire State \u00e9 obrigat\u00f3rio, al\u00e9m de outros lugares como o Central Park, Top of Rock, Est\u00e1tua da Liberdade, etc.<\/p>\n<p>Muita gente fala que \u00e9 bobagem ir \u00e0 Est\u00e1tua da Liberdade, e eu n\u00e3o fui. V\u00e1! N\u00e3o importa\u00a0o pre\u00e7o, pois, dependendo de como \u00e9 a sua vida n\u00e3o\u00a0estar\u00e1 sempre por l\u00e1.\u00a0S\u00f3 estive no Empire State, e \u00e9 muito legal ver a cidade l\u00e1 do alto.<\/p>\n<p>O Central Park, bem, s\u00f3 ficando um dia inteiro para conhecer, e n\u00e3o pude fazer isso.<\/p>\n<p>H\u00e1 alguns lugares para se fazer compras de roupas a eletr\u00f4nicos. Se comparar com o Brasil algumas coisas compensam.<\/p>\n<p>O transporte por metr\u00f4 \u00e9 bem curioso, e serve boa parte da cidade. \u00c9 s\u00f3 comprar o MetroCard, se ficar uma semana compensa comprar o semanal, e se divertir pela cidade.<\/p>\n<p>Sempre falo para as pessoas: o melhor mesmo \u00e9 estar l\u00e1 para sentir o ambiente, como em qualquer outra cidade, pois n\u00e3o parava quieto em lugar algum. Sempre entrei em tudo quanto \u00e9 rua, passeava por caminhos diferentes, etc.<\/p>\n<figure style=\"width: 480px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" \" title=\"Sul de Manhattan\" alt=\"\" src=\"http:\/\/mariano.viveiros.nom.br\/album\/nyc\/imagens\/imagem_43.jpg\" width=\"480\" height=\"360\" \/><figcaption class=\"wp-caption-text\">Sul de Manhattan \u00e0 noite<\/figcaption><\/figure>\n<p style=\"text-align: center;\">Recomendo algo para quem quer esquecer a vida: passear pela orla do Rio Hudson, ou a pra\u00e7a mais ao sul da ilha de Manhattan, ver o p\u00f4r do sol, caminhar, pensar no que quiser.<\/p>\n<p>&nbsp;<\/p>\n<p>Quando eu olho para tr\u00e1s eu vejo que tinha muito mais coisas para se ver e fazer&#8230;<\/p>\n<p>&#8230;e n\u00e3o pensem que precisa gastar muito dinheiro para isso!<\/p>\n<p>Fiz poucas coisas, mas em momento algum fiquei parado. Encerrei a minha viagem vendo uma bela paisagem na caminhada que fiz beirando o Rio Hudson. H\u00e1 muitos lugares de belas paisagens por l\u00e1. N\u00e3o h\u00e1 s\u00f3 pr\u00e9dios, ou uma selva de pedra.<\/p>\n<p>Evolua mais nos pensamentos e conhe\u00e7am New York! \ud83d\ude42 Dia e noite, com sol e chuva, \u00e9 interessante e tem o que ver e fazer.<\/p>\n<figure style=\"width: 480px\" class=\"wp-caption aligncenter\"><img loading=\"lazy\" decoding=\"async\" class=\" \" title=\"Rio Hudson\" alt=\"\" src=\"http:\/\/mariano.viveiros.nom.br\/album\/nyc\/imagens\/imagem_85.jpg\" width=\"480\" height=\"360\" \/><figcaption class=\"wp-caption-text\">Por do sol na orla do Rio Hudson<\/figcaption><\/figure>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>De todas as minhas viagens a mais dif\u00edcil seria essa, se eu n\u00e3o fizesse um planejamento antes. E n\u00e3o \u00e9 que foi f\u00e1cil! A facilidade se deve ao trabalho que tive anos antes de ir, desde os estudos da l\u00edngua inglesa at\u00e9 o dinheiro poupado para poder bancar tudo. Agora, sobre New York: do mesmo &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mariano.viveiros.nom.br\/blog\/2013\/08\/20\/new-york-eu-fui\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;New York &#8211; Eu fui!&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20,4],"tags":[177,178,179,180,181],"class_list":["post-322","post","type-post","status-publish","format-standard","hentry","category-viagem","category-vida","tag-estados-unidos","tag-manhattan","tag-new-york","tag-nyc","tag-usa"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=322"}],"version-history":[{"count":2,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/322\/revisions"}],"predecessor-version":[{"id":325,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/322\/revisions\/325"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}