{"id":372,"date":"2014-07-08T13:54:13","date_gmt":"2014-07-08T16:54:13","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=372"},"modified":"2014-07-08T13:54:13","modified_gmt":"2014-07-08T16:54:13","slug":"o-que-eu-quero-para-daqui-a-cinco-anos","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2014\/07\/08\/o-que-eu-quero-para-daqui-a-cinco-anos\/","title":{"rendered":"O que eu quero para daqui a cinco anos"},"content":{"rendered":"<p>J\u00e1 fizeram esta pergunta para mim h\u00e1 muito tempo atr\u00e1s, perguntando o que gostaria de ser ou fazer no meu futuro, colocando um prazo curto determinado de cinco anos. Bem, em cada per\u00edodo da minha vida um pensamento diferente sobre o futuro.<\/p>\n<p>H\u00e1 cinco anos eu tinha um pensamento diferente do que tenho hoje, pensava em fazer outras coisas, e fazia algumas coisas diferentes, minha atividade era outra. Hoje tenho outros objetivos, minha vida teve uma pequena mudan\u00e7a, e agora tenho outros pensamentos sobre meu futuro.<\/p>\n<p>Recentemente, com minha mudan\u00e7a de moradia, come\u00e7o a pensar de forma diferente sobre o que quero, e o que realmente preciso. Vejo as minhas capacidades em me adaptar \u00e0s mudan\u00e7as, e sinto mais seguran\u00e7a nas minhas tomadas de decis\u00e3o.<\/p>\n<p>Claro que h\u00e1 um ano atr\u00e1s n\u00e3o pensava que estaria do jeito que estou agora, e nem planejava isso, mas, quando vi a necessidade de mudar, a motiva\u00e7\u00e3o para que isso acontecesse me fez planejar calmamente, com um pouco de estudo, enfim tomei a decis\u00e3o e mudei de casa, que \u00e9 um primeiro passo para outras mudan\u00e7as importantes. E isso \u00e9 um passo fundamental para a minha evolu\u00e7\u00e3o.<\/p>\n<p>Fiz tudo com que fosse do jeito mais seguro poss\u00edvel, sem ficar em devaneios, pois conhe\u00e7o o meu potencial.<\/p>\n<p>Mas, o que eu quero para daqui a cinco anos?<\/p>\n<p>\u00c9 uma pergunta pessoal, e que a resposta depende de quem est\u00e1 perguntando, e da situa\u00e7\u00e3o, mas que penso em estar em uma situa\u00e7\u00e3o melhor, isso sim \u00e9 certeza!<\/p>\n<p>Eu estava bem h\u00e1 cinco anos, vejo que estou melhor agora, tenho em minhas m\u00e3os o poder da decis\u00e3o do que quero para meu futuro, e estou consciente disso.<\/p>\n<p>Muitas novidades ocorrerem durante esse tempo, coisas que eu nem imaginava que aconteceriam, mas uma coisa fundamental foi o desapego, ou coragem para mudar, trocar o que eu tinha para o que tenho, o que eu era para o que eu sou.<\/p>\n<p>O passado foi\u00a0 importante, mas preciso ficar nele, e com tudo o que eu tive. Uso o passado como uma base para um futuro melhor.<\/p>\n<p>O que farei daqui pra frente? Quem est\u00e1 a minha volta sabe os meus esfor\u00e7os. E para quem for necess\u00e1rio responderei melhor esta pergunta!<\/p>\n<p>Algumas coisas importantes para o meu futuro s\u00e3o:<\/p>\n<ul>\n<li>Conhecimento e aprendizagem: continuo os meus estudos, tanto na \u00e1rea que trabalho quanto em outras coisas interessantes e importantes;<\/li>\n<li>Finan\u00e7as: sei que preciso de dinheiro no futuro, ent\u00e3o tenho que saber lidar com isso;<\/li>\n<li>Moradia: posso aproveitar para mudar de casa mais vezes, mas com a seguran\u00e7a de saber para onde vou;<\/li>\n<li>Sentimental \/ espiritual: sempre trabalho a minha mente, pois \u00e9 ela afetada diretamente por qualquer decis\u00e3o que eu tomar;<\/li>\n<li>Fam\u00edlia: tenho em mente o que pode acontecer, as possibilidades de estar acompanhado ou n\u00e3o.<\/li>\n<\/ul>\n<p>As pessoas sendo um pouco racionais podem fazer isso que estou fazendo, e se fizerem melhor ser\u00e3o muito evolu\u00eddas, ajudando a si mesmo, e ao mundo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>J\u00e1 fizeram esta pergunta para mim h\u00e1 muito tempo atr\u00e1s, perguntando o que gostaria de ser ou fazer no meu futuro, colocando um prazo curto determinado de cinco anos. Bem, em cada per\u00edodo da minha vida um pensamento diferente sobre o futuro. H\u00e1 cinco anos eu tinha um pensamento diferente do que tenho hoje, pensava &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mariano.viveiros.nom.br\/blog\/2014\/07\/08\/o-que-eu-quero-para-daqui-a-cinco-anos\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;O que eu quero para daqui a cinco anos&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4],"tags":[15],"class_list":["post-372","post","type-post","status-publish","format-standard","hentry","category-vida","tag-futuro"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/372","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=372"}],"version-history":[{"count":2,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/372\/revisions"}],"predecessor-version":[{"id":375,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/372\/revisions\/375"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}