{"id":48,"date":"2009-11-15T23:04:52","date_gmt":"2009-11-16T01:04:52","guid":{"rendered":"http:\/\/mariano.viveiros.nom.br\/blog\/?p=48"},"modified":"2017-04-19T09:52:09","modified_gmt":"2017-04-19T12:52:09","slug":"oia-o-trem","status":"publish","type":"post","link":"https:\/\/mariano.viveiros.nom.br\/blog\/2009\/11\/15\/oia-o-trem\/","title":{"rendered":"\u00d3ia o trem"},"content":{"rendered":"<p>O que eu n\u00e3o fa\u00e7o para viajar de trem? O que fiz, al\u00e9m de encher o saco dos amigos, foi esperar a hora de ir embora de uma balada s\u00f3 para comprar as passagens. Mas n\u00e3o para por a\u00ed: conhecer todas as capitais da regi\u00e3o Sudeste do Brasil precisou de um bom plano, uma boa estrat\u00e9gia. O resultado foi al\u00e9m do esperado, e esta viagem superou as minhas expectativas.<\/p>\n<p>O que eu queria primeiro era viajar pela Estrada de Ferro Vit\u00f3ria a Minas (EFVM), mantida pela Companhia Vale (Vale do Rio Doce).<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" aligncenter\" src=\"http:\/\/mariano.viveiros.nom.br\/album\/bh-vitoria-rio\/imagens\/imagem_14.jpg\" width=\"400\" height=\"300\" \/><\/p>\n<p>Sa\u00ed de uma capital, onde moro, S\u00e3o Paulo. Fui a Belo Horizonte, aguardar ansiosamente a viagem de trem para Vit\u00f3ria, que na verdade vai para Cariacica. Aproveitei para conhecer a capital capixaba, pois, nunca passou pela minha cabe\u00e7a fazer algo em Esp\u00edrito Santo.<\/p>\n<p>Algo foi muito especial para mim: a quantidade de pessoas que eu conversei durante uma viagem de trem. Por ficar em uma &#8220;varanda&#8221;, em p\u00e9, fotografando, as pessoas puxavam assunto, dos mais variados, pessoas bacanas, e a viagem de 13 horas passou tranquilamente.<\/p>\n<p>Chegando em Vit\u00f3ria, eu, que nunca gostei de barcos, navios, botes, transatl\u00e2nticos, veleiros, etc., mas, ao ver o Polar Queen, da Acergy, atracado no Porto, \u00e0 noite, todo iluminado, brilhando, pois eu nunca tinha visto um navio de perto, e desci de um \u00f4nibus ao lado deste trambolh\u00e3o de a\u00e7o.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\" aligncenter\" src=\"http:\/\/mariano.viveiros.nom.br\/album\/bh-vitoria-rio\/imagens\/imagem_59.jpg\" width=\"400\" height=\"300\" \/><\/p>\n<p style=\"text-align: center;\"><em>Este navio serve para lan\u00e7ar dutos em alto mar, para escoar a produ\u00e7\u00e3o da Petrobras.<\/em><\/p>\n<p style=\"text-align: left;\">Por sorte esta era a minha vista do quarto do hotel! Esta fotografia acima era o que eu via.<\/p>\n<p style=\"text-align: left;\">Passear por Vit\u00f3ria, Vila Velha, pegar um \u00f4nibus errado e parar em Serra, serviu para passar o tempo, pois, a viagem para o Rio de Janeiro era a \u00faltima etapa. Esta seria feita s\u00f3 para agradar minha m\u00e3e, que gostaria de andar por Copacabana e Ipanema.<\/p>\n<p style=\"text-align: left;\">Nada de tiros, nem arrast\u00e3o. S\u00f3 fui ao Rio descansar.<\/p>\n<p style=\"text-align: left;\">Encerro minha viagem com um belo apag\u00e3o! E o Rio n\u00e3o estava sozinho nessa escurid\u00e3o. Parte do Brasil, e o Paraguai, estava junto.<\/p>\n<p style=\"text-align: left;\"><img loading=\"lazy\" decoding=\"async\" class=\" aligncenter\" src=\"http:\/\/mariano.viveiros.nom.br\/album\/bh-vitoria-rio\/imagens\/imagem_85.jpg\" width=\"400\" height=\"300\" \/><\/p>\n<p style=\"text-align: left;\">Vejam algumas fotografias desta viagem, e outras, no meu site: <a href=\"http:\/\/mariano.viveiros.nom.br\" target=\"_blank\">mariano.viveiros.nom.br<\/a><\/p>\n<p style=\"text-align: left;\">Moral da hist\u00f3ria: para viajar em uma das duas linhas trens de viagens ativas no Brasil, a EFVM, viajei por todas as capitais dos estados do Sudeste do Brasil, aproveitando a oportunidade.<\/p>\n<p style=\"text-align: left;\">Agora posso dizer que eu j\u00e1 viajei de trem!<\/p>\n<div style=\"text-align: center;\"><em><strong>O Trem Das 7<\/strong><br \/>\nRaul Seixas<\/em><\/div>\n<p><em>\u00d3i, \u00f3i o trem, vem surgindo de tr\u00e1s das montanhas azuis, olha o trem<br \/>\n\u00d3i, \u00f3i o trem, vem trazendo de longe as cinzas do velho \u00e9on<\/em><\/p>\n<p>\u00d3i, j\u00e1 \u00e9 vem, fumegando, apitando, chamando os que sabem do trem<br \/>\n\u00d3i, \u00e9 o trem, n\u00e3o precisa passagem nem mesmo bagagem no trem<\/p>\n<p>Quem vai chorar, quem vai sorrir ?<br \/>\nQuem vai ficar, quem vai partir ?<br \/>\nPois o trem est\u00e1 chegando, t\u00e1 chegando na esta\u00e7\u00e3o<br \/>\n\u00c9 o trem das sete horas, \u00e9 o \u00faltimo do sert\u00e3o, do sert\u00e3o<\/p>\n<p>\u00d3i, olhe o c\u00e9u, j\u00e1 n\u00e3o \u00e9 o mesmo c\u00e9u que voc\u00ea conheceu, n\u00e3o \u00e9 mais<br \/>\nV\u00ea, \u00f3i que c\u00e9u, \u00e9 um c\u00e9u carregado e rajado, suspenso no ar<\/p>\n<p>V\u00ea, \u00e9 o sinal, \u00e9 o sinal das trombetas, dos anjos e dos guardi\u00f5es<br \/>\n\u00d3i, l\u00e1 vem Deus, deslizando no c\u00e9u entre brumas de mil megatons<\/p>\n<p>\u00d3i, olhe o mal, vem de bra\u00e7os e abra\u00e7os com o bem num romance astral<\/p>\n<p>Am\u00e9m.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O que eu n\u00e3o fa\u00e7o para viajar de trem? O que fiz, al\u00e9m de encher o saco dos amigos, foi esperar a hora de ir embora de uma balada s\u00f3 para comprar as passagens. Mas n\u00e3o para por a\u00ed: conhecer todas as capitais da regi\u00e3o Sudeste do Brasil precisou de um bom plano, uma boa &hellip; <\/p>\n<p class=\"link-more\"><a href=\"https:\/\/mariano.viveiros.nom.br\/blog\/2009\/11\/15\/oia-o-trem\/\" class=\"more-link\">Continue reading<span class=\"screen-reader-text\"> &#8220;\u00d3ia o trem&#8221;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[20],"tags":[27,28,29,30,31],"class_list":["post-48","post","type-post","status-publish","format-standard","hentry","category-viagem","tag-belo-horizonte","tag-rio","tag-trem","tag-viagem","tag-vitoria"],"_links":{"self":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/48","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/comments?post=48"}],"version-history":[{"count":6,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/48\/revisions"}],"predecessor-version":[{"id":469,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/posts\/48\/revisions\/469"}],"wp:attachment":[{"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/media?parent=48"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/categories?post=48"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/mariano.viveiros.nom.br\/blog\/wp-json\/wp\/v2\/tags?post=48"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}